{"id":24,"date":"2016-07-18T14:52:03","date_gmt":"2016-07-18T14:52:03","guid":{"rendered":"https:\/\/www.labotanica.ro\/?page_id=24"},"modified":"2025-07-11T15:50:39","modified_gmt":"2025-07-11T15:50:39","slug":"shortcodes","status":"publish","type":"page","link":"https:\/\/www.labotanica.ro\/index.php\/shortcodes\/","title":{"rendered":"Shortcodes"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"columns_wrap sc_columns columns_nofluid sc_columns_count_2\"><div class=\"column-1_2 sc_column_item sc_column_item_1 odd first\"><div class=\"sc_section\"><div class=\"sc_section_inner\"><div class=\"sc_section_content_wrap\"><h3 class=\"sc_title sc_title_regular\" style=\"margin-top: -0.25em !important;\">Video<\/h3><video class=\"sc_video\" src=\"https:\/\/player.vimeo.com\/video\/118330684\" width=\"100%\" height=\"\" data-width=\"100%\" data-height=\"\" data-ratio=\"16:9\" poster=\"https:\/\/www.labotanica.ro\/wp-content\/uploads\/2016\/07\/post-3.jpg\" data-image=\"https:\/\/www.labotanica.ro\/wp-content\/uploads\/2016\/07\/post-3.jpg\" data-class=\"margin_bottom_tiny\" style=\"width:100%;\" autoplay=\"autoplay\" controls=\"controls\" loop=\"loop\"><\/video><\/div><\/div><\/div><\/div><div class=\"column-1_2 sc_column_item sc_column_item_2 even\"><div class=\"sc_section\"><div class=\"sc_section_inner\"><div class=\"sc_section_content_wrap\"><h3 class=\"sc_title sc_title_regular\" style=\"margin-top: -0.25em !important;\">Gallery<\/h3><div id=\"sc_slider_1527306323\" class=\"sc_slider sc_slider_swiper swiper-slider-container sc_slider_nocontrols sc_slider_pagination sc_slider_bg\" data-interval=\"6844\" style=\"width:100%;\"><div class=\"slides swiper-wrapper\" style=\"\"><div class=\"swiper-slide\" style=\"background-image:url(https:\/\/www.labotanica.ro\/wp-content\/uploads\/2016\/07\/post-2.jpg);width:100%;\"><\/div><div class=\"swiper-slide\" style=\"background-image:url(https:\/\/www.labotanica.ro\/wp-content\/uploads\/2016\/07\/post-1.jpg);width:100%;\"><\/div><div class=\"swiper-slide\" style=\"background-image:url(https:\/\/www.labotanica.ro\/wp-content\/uploads\/2016\/07\/post-3.jpg);width:100%;\"><\/div><\/div><div class=\"sc_slider_pagination_wrap\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"sc_line sc_line_position_center_center sc_line_style_solid margin_top_huge margin_bottom_huge\" style=\"border-top-style:solid;\"><\/div><div class=\"columns_wrap sc_columns columns_nofluid sc_columns_count_2\"><div class=\"column-1_2 sc_column_item sc_column_item_1 odd first\"><h3 class=\"sc_title sc_title_regular margin_top_null\">Audio<\/h3><audio class=\"sc_audio\" src=\"https:\/\/www.labotanica.ro\/wp-content\/uploads\/2016\/07\/sample-melody.mp3\" width=\"\" height=\"\" data-title=\"Lily Hunter\" data-author=\"Insert Audio Title Here\"><\/audio><\/div><div class=\"column-1_2 sc_column_item sc_column_item_2 even\"><h3 class=\"sc_title sc_title_regular margin_top_null\">Progress Bar<\/h3><div id=\"sc_skills_diagram_1455232355\" class=\"sc_skills sc_skills_pie sc_skills_compact_off\" data-type=\"pie\" data-caption=\"Skills\"><div class=\"columns_wrap sc_skills_columns sc_skills_columns_3\"><div class=\"sc_skills_column column-1_3\"><div class=\"sc_skills_item sc_skills_style_1 odd first\"><canvas id=\"sc_skills_canvas_361740356_canvas\"><\/canvas><div class=\"sc_skills_total\" data-start=\"0\" data-stop=\"80\" data-step=\"1\" data-steps=\"100\" data-max=\"100\" data-speed=\"37\" data-duration=\"2960\" data-color=\"#aece89\" data-bg_color=\"#f1f6f5\" data-border_color=\"#ffffff\" data-cutout=\"96\" data-easing=\"easeOutCirc\" data-ed=\"%\">0%<\/div><\/div><div class=\"sc_skills_info\"><div class=\"sc_skills_label\" style=\"\">Graphic Design<\/div><\/div><\/div><div class=\"sc_skills_column column-1_3\"><div class=\"sc_skills_item sc_skills_style_1 even\"><canvas id=\"sc_skills_canvas_679207654_canvas\"><\/canvas><div class=\"sc_skills_total\" data-start=\"0\" data-stop=\"75\" data-step=\"1\" data-steps=\"100\" data-max=\"100\" data-speed=\"33\" data-duration=\"2475\" data-color=\"#aece89\" data-bg_color=\"#f1f6f5\" data-border_color=\"#ffffff\" data-cutout=\"96\" data-easing=\"easeOutCirc\" data-ed=\"%\">0%<\/div><\/div><div class=\"sc_skills_info\"><div class=\"sc_skills_label\" style=\"\">HTML & CSS3<\/div><\/div><\/div><div class=\"sc_skills_column column-1_3\"><div class=\"sc_skills_item sc_skills_style_1 odd\"><canvas id=\"sc_skills_canvas_732649260_canvas\"><\/canvas><div class=\"sc_skills_total\" data-start=\"0\" data-stop=\"90\" data-step=\"1\" data-steps=\"100\" data-max=\"100\" data-speed=\"31\" data-duration=\"2790\" data-color=\"#aece89\" data-bg_color=\"#f1f6f5\" data-border_color=\"#ffffff\" data-cutout=\"96\" data-easing=\"easeOutCirc\" data-ed=\"%\">0%<\/div><\/div><div class=\"sc_skills_info\"><div class=\"sc_skills_label\" style=\"\">Illustration<\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"sc_line sc_line_position_center_center sc_line_style_solid margin_top_huge margin_bottom_huge\" style=\"border-top-style:solid;\"><\/div><div class=\"columns_wrap sc_columns columns_nofluid sc_columns_count_2\"><div class=\"column-1_2 sc_column_item sc_column_item_1 odd first\"><h3 class=\"sc_title sc_title_regular margin_top_null\">Countdown<\/h3><div id=\"sc_countdown_430162565\" class=\"sc_countdown sc_countdown_style_1 alignleft margin_top_null\" style=\"````\" data-date=\"2026-05-17\" data-time=\"12:20:20\"><div class=\"sc_countdown_item sc_countdown_days\"><span class=\"sc_countdown_digits\"><span><\/span><span><\/span><span><\/span><\/span><span class=\"sc_countdown_label\">Days<\/span><\/div><div class=\"sc_countdown_item sc_countdown_hours\"><span class=\"sc_countdown_digits\"><span><\/span><span><\/span><\/span><span class=\"sc_countdown_label\">Hours<\/span><\/div><div class=\"sc_countdown_item sc_countdown_minutes\"><span class=\"sc_countdown_digits\"><span><\/span><span><\/span><\/span><span class=\"sc_countdown_label\">Minutes<\/span><\/div><div class=\"sc_countdown_item sc_countdown_seconds\"><span class=\"sc_countdown_digits\"><span><\/span><span><\/span><\/span><span class=\"sc_countdown_label\">Seconds<\/span><\/div><div class=\"sc_countdown_placeholder hide\"><\/div><\/div><\/div><div class=\"column-1_2 sc_column_item sc_column_item_2 even\"><h3 class=\"sc_title sc_title_regular margin_top_null\">Skills<\/h3><div id=\"sc_skills_diagram_1353417094\" class=\"sc_skills sc_skills_bar sc_skills_horizontal\" style=\"width:93%;\" data-type=\"bar\" data-caption=\"Skills\" data-dir=\"horizontal\"><div class=\"sc_skills_info\"><div class=\"sc_skills_label\" style=\"\">Graphic design<\/div><\/div><div class=\"sc_skills_item sc_skills_style_1 odd first\"><div class=\"sc_skills_count\" style=\"background-color:; border-color:#eeaa9c\"><div class=\"sc_skills_total\" data-start=\"0\" data-stop=\"85\" data-step=\"1\" data-max=\"100\" data-speed=\"17\" data-duration=\"1445\" data-ed=\"%\">0%<\/div><\/div><\/div><div class=\"sc_skills_info\"><div class=\"sc_skills_label\" style=\"\">HTML5 & Css3<\/div><\/div><div class=\"sc_skills_item sc_skills_style_1 even\"><div class=\"sc_skills_count\" style=\"background-color:; border-color:#eeaa9c\"><div class=\"sc_skills_total\" data-start=\"0\" data-stop=\"50\" data-step=\"1\" data-max=\"100\" data-speed=\"34\" data-duration=\"1700\" data-ed=\"%\">0%<\/div><\/div><\/div><div class=\"sc_skills_info\"><div class=\"sc_skills_label\" style=\"\">Web design<\/div><\/div><div class=\"sc_skills_item sc_skills_style_1 odd\"><div class=\"sc_skills_count\" style=\"background-color:; border-color:#eeaa9c\"><div class=\"sc_skills_total\" data-start=\"0\" data-stop=\"45\" data-step=\"1\" data-max=\"100\" data-speed=\"21\" data-duration=\"945\" data-ed=\"%\">0%<\/div><\/div><\/div><div class=\"sc_skills_info\"><div class=\"sc_skills_label\" style=\"\">WordPress<\/div><\/div><div class=\"sc_skills_item sc_skills_style_1 even\"><div class=\"sc_skills_count\" style=\"background-color:; border-color:#eeaa9c\"><div class=\"sc_skills_total\" data-start=\"0\" data-stop=\"70\" data-step=\"1\" data-max=\"100\" data-speed=\"17\" data-duration=\"1190\" data-ed=\"%\">0%<\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"sc_line sc_line_position_center_center sc_line_style_solid margin_top_huge margin_bottom_huge\" style=\"border-top-style:solid;\"><\/div><h3 class=\"sc_title sc_title_regular sc_align_center margin_top_null\" style=\"text-align:center;\">Price Plans<\/h3><div class=\"columns_wrap sc_columns columns_nofluid sc_columns_count_3\"><div class=\"column-1_3 sc_column_item sc_column_item_1 odd first\"><div class=\"sc_price_block sc_price_block_style_1\"><div class=\"featured_image\"><img decoding=\"async\" alt=\"Bouquets\" src=\"https:\/\/www.labotanica.ro\/wp-content\/uploads\/2016\/07\/price_plan_img1.jpg\"><\/div><div class=\"sc_price_block_title\"><span>Bouquets<\/span><\/div><div class=\"sc_price_block_description\"><\/p>\n<ul>\n<li>Bridal Bouquets<\/li>\n<li>Bridesmaids&#8217; Bouquets<\/li>\n<li>Corsages<\/li>\n<li>Boutonnieres<\/li>\n<\/ul>\n<p><\/div><div class=\"sc_price_block_money\"><div class=\"sc_price\"><span>From <\/span><span class=\"sc_price_currency\">$<\/span><span class=\"sc_price_money\">399.00<\/span><\/div><\/div><div class=\"sc_price_block_link\"><a href=\"\/shop\/\" class=\"sc_button sc_button_square sc_button_style_filled sc_button_size_small\">order now<\/a><\/div><\/div><\/div><div class=\"column-1_3 sc_column_item sc_column_item_2 even\"><div class=\"sc_price_block sc_price_block_style_1\"><div class=\"featured_image\"><img decoding=\"async\" alt=\"Ceremony+ Bouquets\" src=\"https:\/\/www.labotanica.ro\/wp-content\/uploads\/2016\/07\/price_plan_img2.jpg\"><\/div><div class=\"sc_price_block_title\"><span>Ceremony+ Bouquets<\/span><\/div><div class=\"sc_price_block_description\"><\/p>\n<ul>\n<li>Bride&#8217;s &amp;\u00a0Bridemaids&#8217; Bouquets<\/li>\n<li>Corsages &amp; Boutonnieres<\/li>\n<li>Ceremony Main Altar<\/li>\n<li>Aisle Pew Markers<\/li>\n<\/ul>\n<p><\/div><div class=\"sc_price_block_money\"><div class=\"sc_price\"><span>From <\/span><span class=\"sc_price_currency\">$<\/span><span class=\"sc_price_money\">799.00<\/span><\/div><\/div><div class=\"sc_price_block_link\"><a href=\"\/shop\/\" class=\"sc_button sc_button_square sc_button_style_filled sc_button_size_small\">order now<\/a><\/div><\/div><\/div><div class=\"column-1_3 sc_column_item sc_column_item_3 odd\"><div class=\"sc_price_block sc_price_block_style_1\"><div class=\"featured_image\"><img decoding=\"async\" alt=\"Full Package\" src=\"https:\/\/www.labotanica.ro\/wp-content\/uploads\/2016\/07\/price_plan_img3.jpg\"><\/div><div class=\"sc_price_block_title\"><span>Full Package<\/span><\/div><div class=\"sc_price_block_description\"><\/p>\n<ul>\n<li>Bride&#8217;s &amp;\u00a0Bridemaids&#8217; Bouquets<\/li>\n<li>Corsages &amp; Boutonnieres<\/li>\n<li>Ceremony\u00a0Decoration<\/li>\n<li>Tables &amp; Cake Decoration<\/li>\n<\/ul>\n<p><\/div><div class=\"sc_price_block_money\"><div class=\"sc_price\"><span>From <\/span><span class=\"sc_price_currency\">$<\/span><span class=\"sc_price_money\">999.00<\/span><\/div><\/div><div class=\"sc_price_block_link\"><a href=\"\/shop\/\" class=\"sc_button sc_button_square sc_button_style_filled sc_button_size_small\">order now<\/a><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"sc_line sc_line_position_center_center sc_line_style_solid margin_top_huge margin_bottom_huge\" style=\"border-top-style:solid;\"><\/div><div class=\"columns_wrap sc_columns columns_nofluid sc_columns_count_5 mape_custom \" data-equal-height=\".sc_column_item\"><div class=\"column-3_5 sc_column_item sc_column_item_1 odd first span_3\"><h3 class=\"sc_title sc_title_regular margin_top_null\">Call to Action<\/h3>[vc_cta h2=&#8221;Exclusive Design by Best Florists&#8221; shape=&#8221;square&#8221; add_button=&#8221;bottom&#8221; btn_title=&#8221;shop now&#8221; btn_shape=&#8221;square&#8221; css=&#8221;.vc_custom_1717476698936{margin-bottom: 0px !important;background-image: url(https:\/\/www.labotanica.ro\/wp-content\/uploads\/2016\/07\/bg_cta.jpg?id=44) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; btn_link=&#8221;url:%2Fshop%2F|||&#8221;]Company was established in 1912 and has been family owned for close to twenty years and has always been proud to serve the area with the freshest flowers.[\/vc_cta]<\/div><div class=\"column-2_5 sc_column_item sc_column_item_4 even span_2 after_span_3\" style=\"overflow:hidden;\"><h3 class=\"sc_title sc_title_regular margin_top_null\">Map<\/h3><div id=\"sc_googlemap_1981241216\" class=\"sc_googlemap\" style=\"width:100%;height:100%;\" data-zoom=\"12\" data-style=\"simple\"><iframe src=\"https:\/\/maps.google.com\/maps?t=m&output=embed&iwloc=near&z=12&q=34.05518655634883,-118.23752014787321\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\" frameborder=\"0\"\n                    aria-label=\"\"><\/iframe><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"sc_line sc_line_position_center_center sc_line_style_solid margin_top_huge margin_bottom_huge\" style=\"border-top-style:solid;\"><\/div><h3 class=\"sc_title sc_title_regular margin_top_null\">Promo Block<\/h3><div class=\"sc_promo sc_promo_size_large\"><div class=\"sc_promo_inner\"><div class=\"sc_promo_image\" style=\"background-image:url(https:\/\/www.labotanica.ro\/wp-content\/uploads\/2016\/07\/bg3.jpg);\"><\/div><div class=\"sc_promo_block sc_align_none\"><div class=\"sc_promo_block_inner\"><h2 class=\"sc_promo_title sc_item_title sc_item_title_without_descr\">Let Us Make Your Wedding Flawless<\/h2><div class=\"sc_promo_button sc_item_button\"><a href=\"\/shop\/\" class=\"sc_button sc_button_square sc_button_style_filled sc_button_size_large\">shop now<\/a><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-24","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.labotanica.ro\/index.php\/wp-json\/wp\/v2\/pages\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labotanica.ro\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.labotanica.ro\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.labotanica.ro\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labotanica.ro\/index.php\/wp-json\/wp\/v2\/comments?post=24"}],"version-history":[{"count":0,"href":"https:\/\/www.labotanica.ro\/index.php\/wp-json\/wp\/v2\/pages\/24\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.labotanica.ro\/index.php\/wp-json\/wp\/v2\/media?parent=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}